{"id":545367,"date":"2026-09-02T08:54:38","date_gmt":"2026-09-02T08:54:38","guid":{"rendered":"https:\/\/livelycity.com\/switzerland\/rente-oder-kapital-aus-der-pensionskasse-bei-vielen-banken-versicherungen-und-experten-drohen-interessenkonflikte-und-fehlberatungen\/"},"modified":"2026-09-02T08:54:38","modified_gmt":"2026-09-02T08:54:38","slug":"rente-oder-kapital-aus-der-pensionskasse-bei-vielen-banken-versicherungen-und-experten-drohen-interessenkonflikte-und-fehlberatungen","status":"publish","type":"post","link":"https:\/\/livelycity.com\/switzerland\/rente-oder-kapital-aus-der-pensionskasse-bei-vielen-banken-versicherungen-und-experten-drohen-interessenkonflikte-und-fehlberatungen\/","title":{"rendered":"Rente oder Kapital aus der Pensionskasse: Bei vielen Banken, Versicherungen und Experten drohen Interessenkonflikte und Fehlberatungen"},"content":{"rendered":"<p>Immer mehr Pensionierte entscheiden sich beim Bezug des Pensionskassen-Verm\u00f6gens f\u00fcr eine Auszahlung anstatt f\u00fcr die Rente. Dieser Entscheid hat Risiken. Der Pensionskassenverband reagiert.<\/p>\n<p><a href=\"https:\/\/www.nzz.ch\/finanzen\/rente-oder-kapital-so-vermeiden-sie-fehlentscheidungen-bei-der-pensionierung-ld.10021795\" target=\"_blank\" class=\"\">https:\/\/www.nzz.ch\/finanzen\/rente-oder-kapital-so-vermeiden-sie-fehlentscheidungen-bei-der-pensionierung-ld.10021795<\/a>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Immer mehr Pensionierte entscheiden sich beim Bezug des Pensionskassen-Verm\u00f6gens f\u00fcr eine Auszahlung anstatt f\u00fcr die Rente. Dieser Entscheid hat Risiken. Der Pensionskassenverband reagiert. https:\/\/www.nzz.ch\/finanzen\/rente-oder-kapital-so-vermeiden-sie-fehlentscheidungen-bei-der-pensionierung-ld.10021795\u00a0<\/p>\n","protected":false},"author":0,"featured_media":545368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-545367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neue-zurcher-zeitung","wpcat-6-id"],"jetpack_featured_media_url":"https:\/\/livelycity.com\/switzerland\/wp-content\/uploads\/2026\/09\/f0813db4-91dd-495e-92b6-187f05d07cd7-RevTae.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/posts\/545367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/comments?post=545367"}],"version-history":[{"count":0,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/posts\/545367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/media\/545368"}],"wp:attachment":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/media?parent=545367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/categories?post=545367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/tags?post=545367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}