{"id":545171,"date":"2026-09-01T17:09:10","date_gmt":"2026-09-01T17:09:10","guid":{"rendered":"https:\/\/livelycity.com\/switzerland\/fur-uber-eine-million-sam-altman-bestellt-7-schweizer-uhren\/"},"modified":"2026-09-01T17:09:10","modified_gmt":"2026-09-01T17:09:10","slug":"fur-uber-eine-million-sam-altman-bestellt-7-schweizer-uhren","status":"publish","type":"post","link":"https:\/\/livelycity.com\/switzerland\/fur-uber-eine-million-sam-altman-bestellt-7-schweizer-uhren\/","title":{"rendered":"F\u00fcr \u00fcber eine Million: Sam Altman bestellt 7 Schweizer Uhren"},"content":{"rendered":"<p>Der Gr\u00fcnder des KI-Unternehmens OpenAI bestellte sieben Spezialanfertigungen beim Schweizer Uhrenhersteller Vanguart. Sie sind wohl f\u00fcr Mitarbeitende gedacht.<\/p>\n<p><a href=\"https:\/\/www.20min.ch\/story\/openai-spezialmodelle-fuer-ueber-eine-million-sam-altman-bestellt-7-schweizer-uhren-103625907\" target=\"_blank\" class=\"\">https:\/\/www.20min.ch\/story\/openai-spezialmodelle-fuer-ueber-eine-million-sam-altman-bestellt-7-schweizer-uhren-103625907<\/a>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Gr\u00fcnder des KI-Unternehmens OpenAI bestellte sieben Spezialanfertigungen beim Schweizer Uhrenhersteller Vanguart. Sie sind wohl f\u00fcr Mitarbeitende gedacht. https:\/\/www.20min.ch\/story\/openai-spezialmodelle-fuer-ueber-eine-million-sam-altman-bestellt-7-schweizer-uhren-103625907\u00a0<\/p>\n","protected":false},"author":0,"featured_media":544955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-545171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-20-minuten","wpcat-3-id"],"jetpack_featured_media_url":"https:\/\/livelycity.com\/switzerland\/wp-content\/uploads\/2026\/09\/26e258e6-213d-4601-ae55-a179c308c816-IjP6mc-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/posts\/545171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/comments?post=545171"}],"version-history":[{"count":0,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/posts\/545171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/media\/544955"}],"wp:attachment":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/media?parent=545171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/categories?post=545171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/tags?post=545171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}