{"id":508313,"date":"2026-07-04T22:30:00","date_gmt":"2026-07-04T22:30:00","guid":{"rendered":"https:\/\/livelycity.com\/switzerland\/hitzewelle-rekord-feuerwerk-und-eine-riesige-trump-show-so-hat-amerika-seinen-250-geburtstag-gefeiert-6\/"},"modified":"2026-07-04T22:30:00","modified_gmt":"2026-07-04T22:30:00","slug":"hitzewelle-rekord-feuerwerk-und-eine-riesige-trump-show-so-hat-amerika-seinen-250-geburtstag-gefeiert-6","status":"publish","type":"post","link":"https:\/\/livelycity.com\/switzerland\/hitzewelle-rekord-feuerwerk-und-eine-riesige-trump-show-so-hat-amerika-seinen-250-geburtstag-gefeiert-6\/","title":{"rendered":"Hitzewelle, Rekord-Feuerwerk und eine riesige Trump-Show: So hat Amerika seinen 250. Geburtstag gefeiert"},"content":{"rendered":"<p>An der grossen Jubil\u00e4umsfeier in Washington pr\u00e4sentierte sich Donald Trump gleich selber als Hauptattraktion. Die Party stand im Zeichen des Wetters \u2013 und der politischen Polarisierung.<\/p>\n<p><a href=\"http:\/\/www.bing.com\/news\/apiclick.aspx?ref=FexRss&amp;aid=&amp;tid=6a4b02c6b9c549839d8da77a0ff2ab52&amp;url=https%3A%2F%2Fwww.nzz.ch%2Finternational%2Fhitzewelle-rekord-feuerwerk-und-eine-grosse-trump-show-wie-amerika-seinen-250-geburtstag-feierte-ld.10014113&amp;c=12667333443209094546&amp;mkt=en-us\" target=\"_blank\" class=\"\">http:\/\/www.bing.com\/news\/apiclick.aspx?ref=FexRss&amp;aid=&amp;tid=6a4b02c6b9c549839d8da77a0ff2ab52&amp;url=https%3A%2F%2Fwww.nzz.ch%2Finternational%2Fhitzewelle-rekord-feuerwerk-und-eine-grosse-trump-show-wie-amerika-seinen-250-geburtstag-feierte-ld.10014113&amp;c=12667333443209094546&amp;mkt=en-us<\/a>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>An der grossen Jubil\u00e4umsfeier in Washington pr\u00e4sentierte sich Donald Trump gleich selber als Hauptattraktion. Die Party stand im Zeichen des Wetters \u2013 und der politischen&#8230;<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-508313","post","type-post","status-publish","format-standard","hentry","category-news","wpcat-2-id"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/posts\/508313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/comments?post=508313"}],"version-history":[{"count":0,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/posts\/508313\/revisions"}],"wp:attachment":[{"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/media?parent=508313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/categories?post=508313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/livelycity.com\/switzerland\/wp-json\/wp\/v2\/tags?post=508313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}